{"id":2258,"date":"2017-03-01T12:28:39","date_gmt":"2017-03-01T10:28:39","guid":{"rendered":"http:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife.jpg"},"modified":"2017-03-01T12:28:39","modified_gmt":"2017-03-01T10:28:39","slug":"mott-getalife","status":"inherit","type":"attachment","link":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/index.php\/escucha-get-a-life-el-nuevo-disco-de-mott\/mott-getalife\/","title":{"rendered":"MOTT getalife"},"author":3,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife-300x300.jpg 300w, https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife-150x150.jpg 150w, https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife-1024x1024.jpg 1024w, https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1200","height":"1200","hwstring_small":"height='96' width='96'","file":"2017\/03\/MOTT-getalife.jpg","sizes":{"thumbnail":{"file":"MOTT-getalife-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife-150x150.jpg"},"medium":{"file":"MOTT-getalife-300x300.jpg","width":"300","height":"300","source_url":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife-300x300.jpg"},"large":{"file":"MOTT-getalife-1024x1024.jpg","width":"1024","height":"1024","source_url":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife-1024x1024.jpg"},"feat_slider":{"file":"MOTT-getalife-575x266.jpg","width":"575","height":"266","source_url":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife-575x266.jpg"},"full":{"file":"MOTT-getalife.jpg","width":1200,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":2257,"source_url":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2017\/03\/MOTT-getalife.jpg","_links":{"self":[{"href":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/index.php\/wp-json\/wp\/v2\/media\/2258"}],"collection":[{"href":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=2258"}]}}