{"id":1186,"date":"2014-03-08T16:13:55","date_gmt":"2014-03-08T14:13:55","guid":{"rendered":"http:\/\/www.mmamm.net\/?p=1186"},"modified":"2014-04-04T16:19:10","modified_gmt":"2014-04-04T14:19:10","slug":"bailando-con-distinto-pie","status":"publish","type":"post","link":"https:\/\/www.mmamm.net\/index.php\/2014\/03\/08\/bailando-con-distinto-pie\/","title":{"rendered":"Bailando con distinto pie"},"content":{"rendered":"<p>Texto publicado originalmente en el blog de <a href=\"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/?p=1242\" target=\"_blank\">T\u00edmpanos y Luci\u00e9rnagas<\/a>:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2014\/03\/142-smalltalk-14-persona-non-grata-joost-benthem11.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-1243\" title=\"Persona Non Grata\" src=\"https:\/\/www.mmamm.net\/timpanosyluciernagas\/wordpress\/wp-content\/uploads\/2014\/03\/142-smalltalk-14-persona-non-grata-joost-benthem11.jpg\" alt=\"\" width=\"500\" height=\"411\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Menos mal que me queda este rato a la semana en el que grabamos el programa, un punto y aparte para compartir, para disfrutar. Siempre en buena compa\u00f1\u00eda. Un lujo en los tiempos que corren.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cada vez me siento menos identificado con esta sociedad del siglo XXI.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cuando observo c\u00f3mo tiende a la homogeneidad, al pensamiento \u00fanico, e incluso esto se impone desde determinados medios.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cuando soy testigo de c\u00f3mo los golpes en el pecho y eso de apuntarse tantos se han convertido en el pan de cada d\u00eda, mientras esa gente vive en realidad encorsetada, acomodada, sometida a las normas y los deseos de la industria. Tarde y mal, si es que llegan.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cuando el pampaneo, el mamoneo, el postureo y el peloteo se ha convertido en una costumbre socialmente aceptada y los trepas, sin asomo ninguno de talento, campan a sus anchas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cuando los que m\u00e1s hablan son precisamente los que m\u00e1s tendr\u00edan que callar.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ante este panorama, no quiero dar lecciones a nadie, no soy quien para hacerlo, me conformo con que me dejen tranquilo, \u201cBailando con distinto pie\u201d.<\/span><\/p>\n<p>&nbsp;<br \/>\n<center><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/5tOjNWkC-nY\" frameborder=\"0\" width=\"560\" height=\"420\"><\/iframe><\/center><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Texto publicado originalmente en el blog de T\u00edmpanos y Luci\u00e9rnagas: Menos mal que me queda este rato a la semana en el que grabamos el programa, un punto y aparte para compartir, para disfrutar. Siempre en buena compa\u00f1\u00eda. Un lujo en los tiempos que corren. Cada vez me siento menos identificado con esta sociedad del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[58],"tags":[773,774],"_links":{"self":[{"href":"https:\/\/www.mmamm.net\/index.php\/wp-json\/wp\/v2\/posts\/1186"}],"collection":[{"href":"https:\/\/www.mmamm.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmamm.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmamm.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmamm.net\/index.php\/wp-json\/wp\/v2\/comments?post=1186"}],"version-history":[{"count":0,"href":"https:\/\/www.mmamm.net\/index.php\/wp-json\/wp\/v2\/posts\/1186\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mmamm.net\/index.php\/wp-json\/wp\/v2\/media?parent=1186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmamm.net\/index.php\/wp-json\/wp\/v2\/categories?post=1186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmamm.net\/index.php\/wp-json\/wp\/v2\/tags?post=1186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}